{"id":988,"date":"2023-01-16T14:03:53","date_gmt":"2023-01-16T19:03:53","guid":{"rendered":"https:\/\/www.fajasbela.com\/product\/pack-empoderate\/"},"modified":"2023-10-21T15:13:38","modified_gmt":"2023-10-21T20:13:38","slug":"pack-empoderate-2","status":"publish","type":"product","link":"https:\/\/fajasbela.com\/en\/product\/pack-empoderate-2\/","title":{"rendered":"Paquete Empod\u00e9rate"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row el_class=&#8221;guia-tallas&#8221;][vc_column]<div class=\"porto-lightbox  btn-tallas inline\"> <a href=\"#j9a0l70k3s6lwca20rjmk5u57ucxcu8\" title=\"SEE SIZE GUIDE\" class=\"porto-popup-content\">SEE SIZE GUIDE<\/a> <div id=\"j9a0l70k3s6lwca20rjmk5u57ucxcu8\" class=\"dialog mfp-hide\">[vc_column_text el_class=&#8221;tablas-tallas&#8221;]<\/p>\n<table>\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">SIZES<\/td>\n<td style=\"text-align: center;\" width=\"139\">PANTS<\/td>\n<td style=\"text-align: center;\" width=\"139\">HIPS<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">XS<\/td>\n<td style=\"text-align: center;\" width=\"139\">26\/28<\/td>\n<td style=\"text-align: center;\" width=\"139\">86 &#8211; 93<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">S<\/td>\n<td style=\"text-align: center;\" width=\"139\">28\/30<\/td>\n<td style=\"text-align: center;\" width=\"139\">94 &#8211; 101<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">M<\/td>\n<td style=\"text-align: center;\" width=\"139\">30\/32<\/td>\n<td style=\"text-align: center;\" width=\"139\">102 &#8211; 109<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">L<\/td>\n<td style=\"text-align: center;\" width=\"139\">32\/34<\/td>\n<td style=\"text-align: center;\" width=\"139\">110 &#8211; 117<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">XL<\/td>\n<td style=\"text-align: center;\" width=\"139\">34\/36<\/td>\n<td style=\"text-align: center;\" width=\"139\">118 &#8211; 125<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"149\">XXL<\/td>\n<td style=\"text-align: center;\" width=\"139\">36 A+<\/td>\n<td style=\"text-align: center;\" width=\"139\">125 A+<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/vc_column_text]<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n","protected":false},"featured_media":1088,"template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_joinchat":[]},"product_brand":[],"product_cat":[69],"product_tag":[],"class_list":["post-988","product","type-product","status-publish","has-post-thumbnail","product_cat-buy-more-save-more","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/product\/988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/media\/1088"}],"wp:attachment":[{"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/media?parent=988"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/product_brand?post=988"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/product_cat?post=988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fajasbela.com\/en\/wp-json\/wp\/v2\/product_tag?post=988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}